{"id":104,"date":"2022-08-30T14:55:49","date_gmt":"2022-08-30T14:55:49","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=104"},"modified":"2022-08-30T14:58:21","modified_gmt":"2022-08-30T14:58:21","slug":"insolito-vendia-fernet-escondido-en-bombuchas-en-la-platea-del-mario-alberto-kempes","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2022\/08\/30\/insolito-vendia-fernet-escondido-en-bombuchas-en-la-platea-del-mario-alberto-kempes\/","title":{"rendered":"INS\u00d3LITO: VEND\u00cdA FERNET ESCONDIDO EN BOMBUCHAS EN LA PLATEA DEL MARIO ALBERTO KEMPES"},"content":{"rendered":"\n<p>Un joven de 23 a\u00f1os fue detenido este s\u00e1bado en la previa de Talleres-Racing por vender alcohol dentro del estadio.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"637\" src=\"https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/173974w850h637c.jpg-1.webp\" alt=\"\" class=\"wp-image-108\" srcset=\"https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/173974w850h637c.jpg-1.webp 850w, https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/173974w850h637c.jpg-1-300x225.webp 300w, https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/173974w850h637c.jpg-1-768x576.webp 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><\/figure>\n\n\n\n<p>Algo ins\u00f3lito ocurri\u00f3 este s\u00e1bado en el estadio Mario Alberto Kempes, minutos antes de que comenzara el partido entre Talleres y Racing. La polic\u00eda detuvo a un joven de 23 a\u00f1os que se encontraba vendiendo, de manera camuflada, fernet en bombuchas, en una de las plateas.<br>Se trata de uno de los vendedores de gaseosas y panchos que trabajaba en la platea Gasparini y fue descubierto minutos antes del duelo entre &#8220;La T&#8221; y Racing.<br>&nbsp;<br>El comisario mayor Daniel Bolloni, director de Planificaci\u00f3n y Dise\u00f1o de la Polic\u00eda, habl\u00f3 con el medio Cadena 3 y cont\u00f3 que trabajaban con informaci\u00f3n que ten\u00edan sobre el il\u00edcito, lo que les permiti\u00f3 concretar la aprehensi\u00f3n.<\/p>\n\n\n\n<p>&nbsp;<br>&#8220;Se lo invita a sacar lo que ten\u00eda en la campera y ah\u00ed saca bombuchas que en el interior ten\u00eda fernet&#8221;, detall\u00f3.<\/p>\n\n\n\n<p>En total, ocultaba seis globos inflados con la bebida alcoh\u00f3lica para comercializar, algo que est\u00e1 prohibido en los estadios de f\u00fatbol del pa\u00eds.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un joven de 23 a\u00f1os fue detenido este s\u00e1bado en la previa de Talleres-Racing por<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/104"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=104"}],"version-history":[{"count":3,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/104\/revisions"}],"predecessor-version":[{"id":109,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/104\/revisions\/109"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}