{"id":1388,"date":"2025-01-02T12:46:30","date_gmt":"2025-01-02T12:46:30","guid":{"rendered":"https:\/\/tusnoticiasya.com\/?p=1388"},"modified":"2025-01-02T12:46:30","modified_gmt":"2025-01-02T12:46:30","slug":"controlan-quema-de-pastizales-a-metros-de-concurrida-avenida","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/01\/02\/controlan-quema-de-pastizales-a-metros-de-concurrida-avenida\/","title":{"rendered":"CONTROLAN QUEMA DE PASTIZALES A METROS DE CONCURRIDA AVENIDA"},"content":{"rendered":"\n<p>El fuego se desat\u00f3 en varios terrenos bald\u00edos cercanos a estructuras. Se dio a pocos metros de una concurrida avenida de la capital correntina.<\/p>\n\n\n\n<p>&nbsp;En horas de la tarde del martes 2 de enero, un incendio de pastizales en la intersecci\u00f3n de las calles Madariaga y Chacabuco de la ciudad de Corrientes.&nbsp;Seg\u00fan inform\u00f3 la Asociaci\u00f3n Civil de Bomberos Voluntarios de Corrientes Capital a trav\u00e9s de sus redes sociales, el aviso lleg\u00f3 a trav\u00e9s del sistema 911 alrededor de las 18:20 horas.<\/p>\n\n\n\n<p>El fuego afect\u00f3 varios terrenos bald\u00edos y se encontraba pr\u00f3ximo a estructuras.&nbsp;<strong>El parte de la entidad no indic\u00f3 acerca de las p\u00e9rdidas o de la existencia de v\u00edctimas.<\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/www.radiosudamericana.com\/notix\/multimedia\/imagenes\/fotos\/2025-01-02\/121048.jpg\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El fuego se desat\u00f3 en varios terrenos bald\u00edos cercanos a estructuras. Se dio a pocos<\/p>\n","protected":false},"author":2,"featured_media":1389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1388"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1388"}],"version-history":[{"count":0,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1389"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}