{"id":1514,"date":"2025-01-07T13:22:19","date_gmt":"2025-01-07T13:22:19","guid":{"rendered":"https:\/\/tusnoticiasya.com\/?p=1514"},"modified":"2025-01-07T13:22:19","modified_gmt":"2025-01-07T13:22:19","slug":"sancionaran-a-quienes-incumplan-la-prohibicion-de-prender-fuego","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/01\/07\/sancionaran-a-quienes-incumplan-la-prohibicion-de-prender-fuego\/","title":{"rendered":"SANCIONAR\u00c1N A QUIENES INCUMPLAN LA PROHIBICI\u00d3N DE PRENDER FUEGO"},"content":{"rendered":"\n<p>El incumplimiento de esta norma en alguna de sus partes har\u00e1 pasible a \u00e9l\/los responsables de las sanciones previstas en la Ley Nacional 26.562 y la mencionada Ley Provincial, sin perjuicios de las restantes sanciones que pudieran corresponder.<\/p>\n\n\n\n<p>Por disposici\u00f3n 01 del 2025, el Ministerio de Producci\u00f3n de Corrientes&nbsp;a trav\u00e9s de su Secretar\u00eda de Desarrollo Foresto Industrial &nbsp;y la Direcci\u00f3n de Recursos Forestales, establece que se suspende la autorizaci\u00f3n de quemas controladas que hubieran sido autorizadas por la Autoridad de Aplicaci\u00f3n de la Ley Provincial N\u00b05590, en todo el territorio correntino, hasta tanto se produzca una modificaci\u00f3n favorable de las condiciones clim\u00e1ticas y metereol\u00f3gicas que permitan la realizaci\u00f3n de dichas pr\u00e1cticas.<\/p>\n\n\n\n<p>El incumplimiento de esta norma en alguna de sus partes har\u00e1 pasible a \u00e9l\/los responsables de las sanciones previstas en la Ley Nacional 26.562 y la mencionada Ley Provincial, sin perjuicios de las restantes sanciones que pudieran corresponder.<\/p>\n\n\n\n<p>Las condiciones de humedad y temperatura en el territorio provincial establecidas por el Servicio Meteorol\u00f3gico Nacional (SMN)\u00a0y los \u00edndices de peligro de incendios establecidos por la Direcci\u00f3n de Recursos Forestales, durante varios d\u00edas seguidos de extremo y muy alto \u00edndice de peligro de incendios, aconsejan actuar con m\u00e1ximas restricciones en la realizaci\u00f3n de pr\u00e1cticas \u00edgneas, atento que los incendios rurales ponen en riesgo la integridad f\u00edsica de los habitantes y combatientes de cuerpos de bomberos y brigadas, causan da\u00f1os en los recursos naturales, las infraestructuras rurales como suburbanas y teniendo en cuenta el impacto colateral en el ambiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El incumplimiento de esta norma en alguna de sus partes har\u00e1 pasible a \u00e9l\/los responsables<\/p>\n","protected":false},"author":2,"featured_media":1515,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1514"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1514"}],"version-history":[{"count":0,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1514\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1515"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1514"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1514"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1514"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}