{"id":1573,"date":"2025-01-09T13:13:56","date_gmt":"2025-01-09T13:13:56","guid":{"rendered":"https:\/\/tusnoticiasya.com\/?p=1573"},"modified":"2025-01-09T13:13:56","modified_gmt":"2025-01-09T13:13:56","slug":"mercedes-anuncian-el-programa-de-la-19o-fiesta-del-chamame","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/01\/09\/mercedes-anuncian-el-programa-de-la-19o-fiesta-del-chamame\/","title":{"rendered":"MERCEDES: ANUNCIAN EL PROGRAMA DE LA 19\u00ba FIESTA DEL CHAMAM\u00c9"},"content":{"rendered":"\n<p>El coraz\u00f3n chamamecero de Mercedes late m\u00e1s fuerte. \u00a1Te invitamos a vivir tres noches llenas de m\u00fasica, tradici\u00f3n y alegr\u00eda, organizadas por la Asociaci\u00f3n del Chamam\u00e9!<\/p>\n\n\n\n<p>Fechas:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Viernes 10 de enero \u2013 A partir de las 21 hs<\/li>\n\n\n\n<li>S\u00e1bado 11 de enero \u2013 A partir de las 22 hs<\/li>\n\n\n\n<li>\u00a0Domingo 12 de enero &#8211;\u00a0A partir de las 22 hs<\/li>\n<\/ul>\n\n\n\n<p>Lugar: Anfiteatro Municipal &#8220;Juli\u00e1n Zini&#8221;<\/p>\n\n\n\n<p>Tambi\u00e9n habr\u00e1:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Feria de artesanos y emprendedores: productos regionales y \u00fanicos.<\/li>\n\n\n\n<li>Patio de comidas y cantinas: sabores t\u00edpicos para compartir en familia.<\/li>\n<\/ul>\n\n\n\n<p><strong>Valor de la entrada:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Viernes 10: $5000<\/li>\n\n\n\n<li>S\u00e1bado 11: $8000<\/li>\n\n\n\n<li>Domingo 12: $5000<\/li>\n<\/ul>\n\n\n\n<p>Tambi\u00e9n podes abonar por las tres noches, a $15000<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El coraz\u00f3n chamamecero de Mercedes late m\u00e1s fuerte. \u00a1Te invitamos a vivir tres noches llenas<\/p>\n","protected":false},"author":2,"featured_media":1574,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1573"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1573"}],"version-history":[{"count":0,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1574"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1573"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1573"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}