{"id":1622,"date":"2025-03-20T21:36:23","date_gmt":"2025-03-20T21:36:23","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=1622"},"modified":"2025-03-20T21:36:23","modified_gmt":"2025-03-20T21:36:23","slug":"tres-motociclistas-transportaban-marihuana-y-fueron-detenidos","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/03\/20\/tres-motociclistas-transportaban-marihuana-y-fueron-detenidos\/","title":{"rendered":"TRES MOTOCICLISTAS TRANSPORTABAN MARIHUANA Y FUERON DETENIDOS"},"content":{"rendered":"\n<p>Efectivos de la Comisar\u00eda de distrito Villa Olivari detuvieron la marcha de dos hombres y una mujer que iban a bordo de dos motocicleta<a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.radiosudamericana.com%2Fnota%2Fpoliciales%2F324147-Tres-motociclistas-transportaban-marihuana-y-fueron-detenidos.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>Tres personas fueron detenidas en un operativo de control vehicular realizado por la Polic\u00eda de Corrientes en la Ruta Nacional N\u00b012, a la altura del kil\u00f3metro 1.239. Durante el procedimiento, se hall\u00f3 marihuana en su poder, adem\u00e1s de dinero en efectivo y tel\u00e9fonos celulares.<\/p>\n\n\n\n<p>El operativo, llevado a cabo por efectivos de la Comisar\u00eda de distrito Villa Olivari, ocurri\u00f3 alrededor de las 12:30, cuando los uniformados detuvieron la marcha de dos motocicletas: una de 150cc en la que viajaban un hombre de 25 a\u00f1os y una mujer de 23, y otra de 110cc conducida por un hombre de 32 a\u00f1os.<\/p>\n\n\n\n<p>Durante la inspecci\u00f3n, los agentes encontraron una mochila con una sustancia de origen vegetal. Tras la intervenci\u00f3n de personal especializado y la realizaci\u00f3n de las pruebas correspondientes, se confirm\u00f3 que se trataba de marihuana, con un peso total de 1,260 kg.<\/p>\n\n\n\n<p>El hecho fue puesto en conocimiento de la Fiscal\u00eda en turno, que orden\u00f3 iniciar actuaciones por presunta infracci\u00f3n a la Ley 23.737 de drogas. Tanto los demorados como los elementos secuestrados fueron trasladados a la dependencia policial, donde se contin\u00faa con la investigaci\u00f3n del caso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Efectivos de la Comisar\u00eda de distrito Villa Olivari detuvieron la marcha de dos hombres y<\/p>\n","protected":false},"author":1,"featured_media":1623,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1622"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1622"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1622\/revisions"}],"predecessor-version":[{"id":1624,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1622\/revisions\/1624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1623"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1622"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1622"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1622"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}