{"id":1640,"date":"2025-04-15T21:57:07","date_gmt":"2025-04-15T21:57:07","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=1640"},"modified":"2025-04-15T21:57:07","modified_gmt":"2025-04-15T21:57:07","slug":"corrientes-semana-santa-con-el-recorrido-de-las-7-iglesias-y-el-via-crucis","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/04\/15\/corrientes-semana-santa-con-el-recorrido-de-las-7-iglesias-y-el-via-crucis\/","title":{"rendered":"CORRIENTES: SEMANA SANTA CON EL RECORRIDO DE LAS 7 IGLESIAS Y EL VIA CRUCIS"},"content":{"rendered":"\n<p>La Semana Santa es un tiempo de reflexi\u00f3n y devoci\u00f3n. Conoce en qu\u00e9 d\u00edas se realiza la visita a las 7 iglesias y\u00a0qu\u00e9 representa. Adem\u00e1s te contamos cuando se realizar\u00e1 el Via<a href=\"https:\/\/www.facebook.com\/sharer.php?u=https%3A%2F%2Fwww.radiosudamericana.com%2Fnota%2Fsociedad%2F325434-Corrientes--Semana-Santa-con-el-recorrido-de-las-7-Iglesias-y-el-Via-Crucis.htm\" target=\"_blank\" rel=\"noreferrer noopener\"><\/a><\/p>\n\n\n\n<p>El recorrido se lleva a cabo principalmente en Jueves Santo, cuando los cat\u00f3licos visitan siete templos en los que&nbsp;se recuerda cada una de las etapas previas a la crucifixi\u00f3n de Cristo.&nbsp;Aunque no existe un orden estricto para realizar la ruta, cada iglesia representa un episodio significativo en la Pasi\u00f3n de Jes\u00fas.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 d\u00edas se realiza el recorrido de las siete iglesias?<\/strong><\/h3>\n\n\n\n<p>El&nbsp;Jueves Santo es la fecha m\u00e1s com\u00fan para el recorrido de las siete iglesias, aunque en algunas ciudades tambi\u00e9n se realiza el Viernes Santo por la ma\u00f1ana. La Semana Santa de 2025 se celebrar\u00e1 en abril, y los d\u00edas clave para esta tradici\u00f3n religiosa ser\u00e1n los siguientes:<\/p>\n\n\n\n<ul>\n<li>Domingo de Ramos (13 de abril):&nbsp;Inicio de la Semana Santa.<\/li>\n\n\n\n<li>Jueves Santo (17 de abril):&nbsp;Conmemoraci\u00f3n de la \u00daltima Cena y recorrido de las siete iglesias.<\/li>\n\n\n\n<li>Viernes Santo (18 de abril):&nbsp;Recuerdo de la crucifixi\u00f3n de Jes\u00fas.<\/li>\n\n\n\n<li>Domingo de Resurrecci\u00f3n (20 de abril):&nbsp;Celebraci\u00f3n de la resurrecci\u00f3n de Jes\u00fas.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>\u00bfQu\u00e9 significa el recorrido por las siete iglesias?<\/strong><\/h3>\n\n\n\n<p>Este&nbsp;acto de fe conmemora los momentos previos a la crucifixi\u00f3n de Jes\u00fas,&nbsp;dividiendo su camino hacia el Calvario en siete estaciones:<\/p>\n\n\n\n<ol>\n<li>Primera iglesia:&nbsp;La \u00daltima Cena y la oraci\u00f3n en el huerto de Getseman\u00ed.<\/li>\n\n\n\n<li>Segunda iglesia:&nbsp;El traslado de Jes\u00fas ante An\u00e1s para ser interrogado.<\/li>\n\n\n\n<li>Tercera iglesia:&nbsp;La comparecencia ante Caif\u00e1s y el juicio del Sanedr\u00edn.<\/li>\n\n\n\n<li>Cuarta iglesia:&nbsp;La presentaci\u00f3n ante Poncio Pilato, quien no encuentra culpa en \u00e9l.<\/li>\n\n\n\n<li>Quinta iglesia:&nbsp;El env\u00edo ante el rey Herodes, que lo ridiculiza y lo devuelve a Pilato.<\/li>\n\n\n\n<li>Sexta iglesia:&nbsp;La segunda comparecencia ante Pilato, quien cede ante la presi\u00f3n y lo condena.<\/li>\n\n\n\n<li>S\u00e9ptima iglesia:&nbsp;El camino al Calvario, donde Jes\u00fas es azotado y carga la cruz.<\/li>\n<\/ol>\n\n\n\n<p>En este recorrido, los fieles meditan sobre el sufrimiento de Cristo y renuevan su compromiso con la fe a trav\u00e9s de la oraci\u00f3n en cada iglesia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Recorrido de las 7 Iglesias en Corrientes Capital y V\u00eda Crucis.&nbsp;<\/strong><\/h3>\n\n\n\n<p>En la ciudad de Corrientes est\u00e1 previsto la recorrida este jueves a las 8 de la ma\u00f1ana: salida desde las &#8220;Terrazas del Paran\u00e1&#8221; (Av. Costanera Gral. San Martin y Tomas Edison).<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Recorrido de Iglesias<\/strong><\/h3>\n\n\n\n<ol>\n<li>Jes\u00fas Nazareno<\/li>\n\n\n\n<li>San Francisco Solano<\/li>\n\n\n\n<li>Nuestra Se\u00f1ora de la Merced<\/li>\n\n\n\n<li>Mar\u00eda Auxiliadora<\/li>\n\n\n\n<li>Santisima Cruz de los Milagros<\/li>\n\n\n\n<li>Santa Rita<\/li>\n\n\n\n<li>Catedral &#8216;Nuestra Se\u00f1ora del Rosario<\/li>\n<\/ol>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Via Crucis en Corrientes Capital<\/strong><\/h3>\n\n\n\n<p>Se realizar\u00e1 el viernes 18 de abril por Av. Costanera General San Mart\u00edn desde Paseo Stella Maris hasta la Avenida 3 de Abril. Ser\u00e1 desde las 19 horas.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Semana Santa es un tiempo de reflexi\u00f3n y devoci\u00f3n. Conoce en qu\u00e9 d\u00edas se<\/p>\n","protected":false},"author":1,"featured_media":1641,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1640"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1640"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1640\/revisions"}],"predecessor-version":[{"id":1642,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1640\/revisions\/1642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1641"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}