{"id":1746,"date":"2025-09-17T14:22:17","date_gmt":"2025-09-17T14:22:17","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=1746"},"modified":"2025-09-17T14:22:17","modified_gmt":"2025-09-17T14:22:17","slug":"prepagas-afiliados-podran-usar-excedentes-de-aportes-para-bajar-cuotas","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/09\/17\/prepagas-afiliados-podran-usar-excedentes-de-aportes-para-bajar-cuotas\/","title":{"rendered":"PREPAGAS: AFILIADOS PODR\u00c1N USAR EXCEDENTES DE APORTES PARA BAJAR CUOTAS"},"content":{"rendered":"\n<p>El Gobierno derogar\u00e1 un art\u00edculo de la resoluci\u00f3n 2400\/2023 y permitir\u00e1 que los afiliados a prepagas usen los excedentes de sus aportes para pagar cuotas m\u00e1s bajas.<\/p>\n\n\n\n<p>El&nbsp;Gobierno&nbsp;anunci\u00f3 este&nbsp;martes&nbsp;que los afiliados a servicios de medicina prepaga podr\u00e1n disponer de los&nbsp;excedentes&nbsp;generados por las derivaciones de sus aportes y utilizarlos para reducir el costo de sus&nbsp;cuotas mensuales. La medida revierte una disposici\u00f3n de la gesti\u00f3n de&nbsp;Alberto Fern\u00e1ndez&nbsp;que imped\u00eda ese uso y que, seg\u00fan fuentes oficiales, perjudic\u00f3 a unos<strong>&nbsp;1,8 millones&nbsp;de empleados en relaci\u00f3n de dependencia.<\/strong><\/p>\n\n\n\n<p>El vocero presidencial,&nbsp;Manuel Adorni, explic\u00f3 que en los pr\u00f3ximos d\u00edas el&nbsp;Ministerio de Salud, a trav\u00e9s de la&nbsp;Superintendencia de Servicios de Salud, dar\u00e1 de baja un art\u00edculo \u201coculto\u201d del anexo de la resoluci\u00f3n&nbsp;2400\/2023, firmada en los \u00faltimos d\u00edas del gobierno anterior. Ese art\u00edculo establec\u00eda que los excedentes de aportes y contribuciones pertenec\u00edan a las empresas y no a los afiliados.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Un perjuicio millonario<\/strong><\/h2>\n\n\n\n<p>De acuerdo con estimaciones oficiales, la aplicaci\u00f3n de esta norma deriv\u00f3 en una retenci\u00f3n indebida de\u00a0<strong>alrededor de\u00a0$180.000 millones\u00a0en casi\u00a0dos a\u00f1os.<\/strong>\u00a0\u201cLos principales afectados fueron los empleados en relaci\u00f3n de dependencia, que ve\u00edan c\u00f3mo sus aportes quedaban \u2018colgados\u2019 sin poder utilizarlos y terminaban en las arcas de las prepagas\u201d, se\u00f1alaron las autoridades.<\/p>\n\n\n\n<p>\u201cEste dinero debe representar un descuento de cuota para los afiliados\u201d, enfatiz\u00f3\u00a0Adorni\u00a0al detallar los alcances de la nueva disposici\u00f3n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>M\u00e1s transparencia en las facturas<\/strong><\/h2>\n\n\n\n<p>El\u00a0Gobierno\u00a0tambi\u00e9n dispuso que las empresas de medicina prepaga deber\u00e1n discriminar en cada factura cu\u00e1nto recibe cada afiliado en concepto de\u00a0subsidios autom\u00e1ticos. Con esta medida, buscan que quede en claro que esos fondos pertenecen a los usuarios y no a las compa\u00f1\u00edas.<\/p>\n\n\n\n<p>La iniciativa responde a uno de los reclamos m\u00e1s frecuentes de los trabajadores en relaci\u00f3n de dependencia, quienes se\u00f1alaban que el sistema vigente les imped\u00eda acceder a&nbsp;<strong>un&nbsp;beneficio leg\u00edtimo&nbsp;de sus propios aportes.<\/strong><\/p>\n\n\n\n<p>Con la modificaci\u00f3n, los afiliados podr\u00e1n finalmente aplicar los excedentes para pagar cuotas m\u00e1s bajas, al tiempo que se espera que el nuevo esquema aporte mayor&nbsp;transparencia&nbsp;y control sobre los fondos que ingresan al sistema de salud privado.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno derogar\u00e1 un art\u00edculo de la resoluci\u00f3n 2400\/2023 y permitir\u00e1 que los afiliados a<\/p>\n","protected":false},"author":1,"featured_media":1747,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1746"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1746"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1746\/revisions"}],"predecessor-version":[{"id":1748,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1746\/revisions\/1748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1747"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1746"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1746"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1746"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}