{"id":1767,"date":"2025-10-14T21:51:20","date_gmt":"2025-10-14T21:51:20","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=1767"},"modified":"2025-10-27T21:54:51","modified_gmt":"2025-10-27T21:54:51","slug":"caso-nora-dalmasso-sobreseyeron-al-principal-sospechoso-del-crimen","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/10\/14\/caso-nora-dalmasso-sobreseyeron-al-principal-sospechoso-del-crimen\/","title":{"rendered":"CASO NORA DALMASSO: SOBRESEYERON AL PRINCIPAL SOSPECHOSO DEL CRIMEN"},"content":{"rendered":"\n<p>Lo decidi\u00f3 la Justicia de C\u00f3rdoba a 19 a\u00f1os del hecho. El plazo para el delito venci\u00f3 a los 15.<\/p>\n\n\n\n<p>La justicia cordobesa&nbsp;absolvi\u00f3 este martes al \u00fanico se\u00f1alado como autor del crimen de Nora Dalmasso.&nbsp;La decisi\u00f3n se tom\u00f3 por prescripci\u00f3n. El hecho ocurri\u00f3 hace 19 a\u00f1os y el plazo para ese delito venci\u00f3 a los 15.<\/p>\n\n\n\n<p>Despu\u00e9s de la\u00a0absoluci\u00f3n de Marcelo Macarr\u00f3n\u00a0en 2022,\u00a0el crimen de\u00a0Nora Dalmasso\u00a0qued\u00f3 impune. No se determin\u00f3 un culpable y ahora, la causa prescribi\u00f3.<\/p>\n\n\n\n<p>Por insistencia de la familia, se continu\u00f3 la&nbsp;investigaci\u00f3n&nbsp;para reconstruir la verdad y encontrar al autor del asesinato. A fines de 2024 y mientras avanzaba el proceso, la&nbsp;aparici\u00f3n de un nuevo sospechoso&nbsp;volvi\u00f3 a poner el caso en boca de todos. Sin embargo, a 19 a\u00f1os del crimen, la Justicia defini\u00f3 que no avanzar\u00e1 m\u00e1s en el intento de esclarecer qu\u00e9 pas\u00f3 el 26 de noviembre de 2006 en R\u00edo Cuarto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lo decidi\u00f3 la Justicia de C\u00f3rdoba a 19 a\u00f1os del hecho. El plazo para el<\/p>\n","protected":false},"author":1,"featured_media":1768,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1767"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1767"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1767\/revisions"}],"predecessor-version":[{"id":1769,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1767\/revisions\/1769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1768"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}