{"id":1788,"date":"2025-11-18T15:32:20","date_gmt":"2025-11-18T15:32:20","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=1788"},"modified":"2025-11-18T15:32:20","modified_gmt":"2025-11-18T15:32:20","slug":"javier-milei-viajara-a-washington-para-asistir-junto-a-donald-trump-al-sorteo-del-mundial-2026","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2025\/11\/18\/javier-milei-viajara-a-washington-para-asistir-junto-a-donald-trump-al-sorteo-del-mundial-2026\/","title":{"rendered":"JAVIER MILEI VIAJAR\u00c1 A WASHINGTON PARA ASISTIR JUNTO A DONALD TRUMP AL SORTEO DEL MUNDIAL 2026"},"content":{"rendered":"\n<p>El Presidente estar\u00e1 en el Kennedy Center de Washington el 5 de diciembre, donde seguir\u00e1 el sorteo del Mundial 2026 desde el palco junto a Donald Trump.<\/p>\n\n\n\n<p>Javier Milei viajar\u00e1 a Washington y para participar del sorteo del Mundial 2026 acompa\u00f1ado por el presidente de Estados Unidos, Donald Trump. El evento se realizar\u00e1 el 5 de diciembre en el Kennedy Center y marcar\u00e1 un nuevo gesto pol\u00edtico en la relaci\u00f3n entre ambos mandatarios.<\/p>\n\n\n\n<p>Seg\u00fan inform\u00f3 NA, la participaci\u00f3n del Presidente qued\u00f3 confirmada a trav\u00e9s de fuentes oficiales vinculadas a la oraganizaci\u00f3n del evento.<\/p>\n\n\n\n<p>El evento se realizar\u00e1 el 5 de diciembre a las 14:00 en la capital estadounidense, y la ceremonia tendr\u00e1 lugar en la sala principal del Kennedy Center, un auditorio con capacidad para 2.442 personas que fue puesto a disposici\u00f3n por Trump gracias a su v\u00ednculo con el presidente de la FIFA, Gianni Infantino.<\/p>\n\n\n\n<p>El viaje ser\u00e1 el n\u00famero 15 de Milei a Estados Unidos desde que asumi\u00f3. Su participaci\u00f3n forma parte de la agenda oficial vinculada al sorteo de la Copa del Mundo 2026 y se enmarca en las relaciones bilaterales entre Argentina y Estados Unidos.<\/p>\n\n\n\n<p>Durante la ceremonia, los mandatarios seguir\u00e1n la definici\u00f3n de los grupos desde el sector destinado a las autoridades presentes.<\/p>\n\n\n\n<p>Un encuentro en el marco del sorteo mundialista<\/p>\n\n\n\n<p>Milei y Trump coincidir\u00e1n en la ceremonia en la que la FIFA sortear\u00e1 los grupos del Mundial 2026, el primero que contar\u00e1 con 48 selecciones y sedes distribuidas entre Estados Unidos, M\u00e9xico y Canad\u00e1. El acto reunir\u00e1 a autoridades deportivas, funcionarios invitados y representantes de los pa\u00edses participantes.<\/p>\n\n\n\n<p>El Kennedy Center fue elegido por la FIFA como sede del sorteo, en un operativo que concentrar\u00e1 a medios internacionales y delegaciones oficiales. La organizaci\u00f3n estadounidense habilit\u00f3 el auditorio principal para el desarrollo del evento.<\/p>\n\n\n\n<p>C\u00f3mo ser\u00e1 el Mundial 2026<\/p>\n\n\n\n<p>El Mundial 2026 ser\u00e1 el primero en contar con 48 equipos (16 m\u00e1s que Qatar 2022) y 16 sedes, constar\u00e1 de 104 partidos (40 m\u00e1s que el anterior) y una ronda eliminatoria adicional.<\/p>\n\n\n\n<p>Dicho torneo se llevar\u00e1 a cabo en Canad\u00e1, M\u00e9xico y Estados Unidos, comenzando en junio de 2026 (fecha a confirmar) y terminando con la final el 19 de julio de 2026. El sorteo definir\u00e1 la composici\u00f3n de los grupos y el orden de los encuentros, paso clave para la organizaci\u00f3n del calendario general.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Presidente estar\u00e1 en el Kennedy Center de Washington el 5 de diciembre, donde seguir\u00e1<\/p>\n","protected":false},"author":1,"featured_media":1789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1788"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=1788"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1788\/revisions"}],"predecessor-version":[{"id":1790,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/1788\/revisions\/1790"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/1789"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=1788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=1788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=1788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}