{"id":208,"date":"2022-10-14T13:10:55","date_gmt":"2022-10-14T13:10:55","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=208"},"modified":"2022-10-14T13:10:56","modified_gmt":"2022-10-14T13:10:56","slug":"otorgaron-la-excarcelacion-a-la-ex-titular-del-registro-de-la-propiedad","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2022\/10\/14\/otorgaron-la-excarcelacion-a-la-ex-titular-del-registro-de-la-propiedad\/","title":{"rendered":"OTORGARON LA EXCARCELACI\u00d3N A LA EX TITULAR DEL REGISTRO DE LA PROPIEDAD"},"content":{"rendered":"\n<p>La escribana Demetrio, quien fuera directora del organismo provincial, quedar\u00e1 en libertad bajo cauci\u00f3n juratoria, seg\u00fan el fallo dispuesto por la juez Gonz\u00e1lez Caba\u00f1a. El fiscal hab\u00eda pedido rechazar la solicitud. En la causa hay m\u00e1s de una veintena de imputados y unos 12 detenidos.<\/p>\n\n\n\n<p>Exactamente a dos mes y dos d\u00edas de ser detenida en el marco de amplios operativos simult\u00e1neos que se implementaron por la causa judicial conocida como la megaestafa por terrenos, la escribana Mar\u00eda Eugenia Demetrio logr\u00f3 ayer que se le otorgue la excarcelaci\u00f3n bajo cauci\u00f3n juratoria.<\/p>\n\n\n\n<p>El fallo emitido por la juez Mar\u00eda Josefina Gonz\u00e1lez Caba\u00f1as, a cargo del Juzgado de Instrucci\u00f3n N\u00b03, dispuso tambi\u00e9n que Demetrio acate un r\u00e9gimen de conducta y restricciones espec\u00edficas, seg\u00fan marca la ley.<\/p>\n\n\n\n<p>Adem\u00e1s, determin\u00f3 &#8220;suspenderla preventivamente de sus funciones como directora del Registro de la Propiedad Inmueble de Corrientes, hasta tanto sea resuelta su situaci\u00f3n legal en este caso penal, comunicando lo resuelto al Ministerio de Hacienda a fin de que tome raz\u00f3n de lo resuelto&#8221;, consign\u00f3.<\/p>\n\n\n\n<p>En esta compleja causa se investiga el accionar de una presunta asociaci\u00f3n il\u00edcita dedicada a quedarse con terrenos de distintos puntos de la provincia, a partir de fraguar t\u00edtulos de propiedad y validarlos como aut\u00e9nticos en organismo provinciales dedicados al rubro. Adem\u00e1s de iniciar juicios sucesorios y quedarse con los predios en cuesti\u00f3n.<\/p>\n\n\n\n<p>La punta del ovillo fueron lotes de la zona de ruta de acceso a Santa Ana. La cantidad de terrenos afectados por este accionar delictivo podr\u00edan ser decenas y decenas.<\/p>\n\n\n\n<p>Asimismo, vale recordar que por el caso hay m\u00e1s de una veintena de imputados, de los cuales al menos 12 permanecen detenidos. Adem\u00e1s de Demetrio, fue detenido el 11 de agosto el titular de la Direcci\u00f3n de Catastro, Narcisco Toffoletti.<\/p>\n\n\n\n<p>En concreto se investigan los delitos de &#8220;asociaci\u00f3n il\u00edcita, estafa, incumplimiento de los deberes de funcionario p\u00fablico, tr\u00e1fico de influencias, negociaciones incompatibles con la funci\u00f3n p\u00fablica, falsificaci\u00f3n de documentos p\u00fablicos, uso de documentos p\u00fablicos falsos, falsedad ideol\u00f3gica de instrumentos p\u00fablicos&#8221;, seg\u00fan la causa judicial.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Excarcelaci\u00f3n<\/h2>\n\n\n\n<p>Para la solicitud de excarcelaci\u00f3n de la escribana Demetrio, sus abogados plantearon en principio que hay situaciones que exponen no s\u00f3lo su inocencia -seg\u00fan indicaron-, sino que tambi\u00e9n representar\u00edan la imposibilidad de que ella entorpezca la investigaci\u00f3n en curso.<\/p>\n\n\n\n<p>A la vez, expusieron que Demetrio ya fue suspendida de su cargo en el mencionado Registro de la Propiedad (resoluci\u00f3n del Ministerio de Hacienda), &#8220;por lo que carece de toda posibilidad de incidir respecto de la prueba documental vinculada al organismo&#8221;, indic\u00f3 la defensa integrada por los abogados Nelson Pessoa y Neri Sebasti\u00e1n Trossero, seg\u00fan consta en el fallo al que tuvo acceso \u00e9poca.<\/p>\n\n\n\n<p>Tambi\u00e9n trajeron a colaci\u00f3n la excarcelaci\u00f3n otorgada recientemente a Mar\u00eda Bernarda Correa, la segunda al mando en el Registro de la Propiedad Inmueble, tambi\u00e9n implicada en el caso que se investiga.<\/p>\n\n\n\n<p>Finalmente, plantearon el hecho de que Demetrio &#8220;sufre ciertas dolencias card\u00edacas&#8221;, tiene 58 a\u00f1os de edad, &#8220;con arraigo familiar y laboral, es madre de cuatro hijos y no posee antecedentes penales&#8221;, expresaron.<\/p>\n\n\n\n<p>A su turno, el fiscal de la causa, Gustavo Roubineau, -y de acuerdo a los considerandos del fallo de Gonz\u00e1lez Caba\u00f1as- consider\u00f3 que &#8220;corresponde se rechace la solicitud impetrada, por cuanto en el caso las razones aportadas por la defensa letrada no alcanzan para desvirtuar la presunci\u00f3n de riesgo procesal latente en caso que Demetrio recupere su libertad&#8221;, expres\u00f3.<\/p>\n\n\n\n<p>Al respecto, se\u00f1al\u00f3 que para hacer dicho planteo se bas\u00f3 &#8220;en el rol que ejerc\u00eda la imputada como directora general del Registro de la Propiedad Inmueble, quien detenta el cargo hace numerosos a\u00f1os y posee conocimientos, habilidades y contactos necesarios para adulterar cualquier prueba. Por tal, aunque estuviera suspendida del cargo, no supone que el riesgo procesal haya desaparecido&#8221;.<\/p>\n\n\n\n<p>Tambi\u00e9n record\u00f3 que varios expedientes incautados por la Justicia &#8220;a simple vista presentan borrones, correcciones y cortes que no deber\u00edan estar presentes en documentos valiosos \u00fanicos que reflejan el asiento registral de un inmueble, pudiendo presumirse que estos fueron manipulados&#8221;, asever\u00f3.<\/p>\n\n\n\n<p>Finalmente, la Juez del caso decidi\u00f3 la excarcelaci\u00f3n solicitada por Demetrio, considerando que &#8220;los riesgos procesales en este momento de la investigaci\u00f3n han mermado, variando as\u00ed la situaci\u00f3n inicial de cuando se rechaz\u00f3 el pedido que fuera confirmado por C\u00e1mara de Apelaciones, sin perjuicio de que a la imputada le deban ser aplicadas otras restricciones menos gravosas, que m\u00e1s adelante pasar\u00e9 a explicar y fundamentar&#8221;.<\/p>\n\n\n\n<p>Dispuso su libertad pero para ello debe cumplir requisitos, como &#8220;fijar domicilio que no podr\u00e1 variar sin comunicarlo previamente al tribunal&#8221;, tambi\u00e9n &#8220;comparecer mensualmente del 1 al 10 de cada mes ante este Juzgado, a efectos de firmar un acta de comparendo&#8221; y la &#8220;prohibici\u00f3n de ausentarse de la provincia y del pa\u00eds&#8221;.<\/p>\n\n\n\n<p>Adem\u00e1s, se dispuso la &#8220;prohibici\u00f3n absoluta de mantener contacto alguno, por cualquier clase de medios (contacto personal, llamadas telef\u00f3nicas y\/o por medios telem\u00e1ticos), con los actuales empleados y funcionarios del Registro de la Propiedad del Inmueble&#8221;. Similar prohibici\u00f3n para el contacto con los dem\u00e1s coimputados de la causa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La escribana Demetrio, quien fuera directora del organismo provincial, quedar\u00e1 en libertad bajo cauci\u00f3n juratoria,<\/p>\n","protected":false},"author":1,"featured_media":209,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/208"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=208"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/208\/revisions"}],"predecessor-version":[{"id":210,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/208\/revisions\/210"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/209"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}