{"id":485,"date":"2023-07-20T13:59:34","date_gmt":"2023-07-20T13:59:34","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=485"},"modified":"2023-07-20T13:59:35","modified_gmt":"2023-07-20T13:59:35","slug":"policia-y-bandido-heridos-tras-un-violento-robo-armado-a-negocio","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2023\/07\/20\/policia-y-bandido-heridos-tras-un-violento-robo-armado-a-negocio\/","title":{"rendered":"POLIC\u00cdA Y BANDIDO, HERIDOS TRAS UN VIOLENTO ROBO ARMADO A NEGOCIO"},"content":{"rendered":"\n<p>El sargento volv\u00eda del trabajo a su casa cuando auxili\u00f3 a la v\u00edctima. Termin\u00f3 con dos dedos quebrados, mientras que el delincuente recibi\u00f3 un balazo en la pierna. D\u00edas atr\u00e1s allanaron su casa y descubrieron gran cantidad de elementos sustra\u00eddos.<\/p>\n\n\n\n<p>Un delincuente y un polic\u00eda que volv\u00eda a su casa de su jornada laboral resultaron heridos en medio de un violento robo ocurrido en la madrugada de ayer en la localidad de Santa Rosa. El maleante intent\u00f3 atacar a pu\u00f1aladas al sargento y este respondi\u00f3 d\u00e1ndole un disparo en la pierna. El bandido, con un extenso prontuario delictivo, adem\u00e1s estaba siendo buscado por su participaci\u00f3n activa en una serie de robos ocurrido en la ciudad, informaron ayer fuentes oficiales.<\/p>\n\n\n\n<p>Todo sucedi\u00f3 en plena madrugada, alrededor de las 4:40, cuando la due\u00f1a de un comercio ubicado por calle Jujuy en el barrio Llamarada dio aviso a su vecino polic\u00eda de que estaba siendo v\u00edctima de un robo por parte de varios j\u00f3venes armados con cuchillos y muy violentos. El polic\u00eda, un sargento de la fuerza provincial, estaba regresando a su casa de su jornada laboral; todav\u00eda vest\u00eda su uniforme. Los delincuentes, al ver que el atraco se frustr\u00f3, comenzaron a destrozar el local.<\/p>\n\n\n\n<p>El polic\u00eda, que vive a media cuadra, lleg\u00f3 hasta el lugar, se identific\u00f3 y puso en fuga a parte de la banda, pero uno de ellos le hizo frente, primero arroj\u00e1ndole una caja con vinos, hiriendo en la mano al sargento quebr\u00e1ndole dos dedos. Al ver que el primer golpe hab\u00eda hecho efecto en el uniformado, el bandido lo atac\u00f3 a cuchillazos, pero el efectivo respondi\u00f3 r\u00e1pidamente, extrajo su arma y apunt\u00f3 a una de las piernas del maleante anulando completamente el ataque y reduci\u00e9ndolo instant\u00e1neamente.<\/p>\n\n\n\n<p>En ese momento llegaron sus camaradas y se hicieron cargo del procedimiento. Para entonces, el fiscal Daniel Lezcano tambi\u00e9n estaba camino a la escena y pudo relevar toda la informaci\u00f3n de lo sucedido.<\/p>\n\n\n\n<p>Fuentes del caso confirmaron a diario \u00e9poca que tanto el sargento Escalante como el delincuente que pretendi\u00f3 apu\u00f1alarlo est\u00e1n fuera de peligro. Al funcionario se le tom\u00f3 declaraci\u00f3n testimonial, ya que la Justicia entiende que el polic\u00eda no solo estaba uniformado y perfectamente identificado al realizar el arresto, sino que varios testigos escucharon cuando dio la voz de &#8220;alto&#8221; antes de ser atacado y disparar su arma reglamentaria. &#8220;No hay causa judicial en contra del polic\u00eda porque actu\u00f3 conforme la ley y en leg\u00edtima defensa&#8221;, explic\u00f3 un vocero judicial. El legajo de investigaci\u00f3n abierto al respecto del hecho fue bajo una causa caratulada como &#8220;robo doblemente calificado, en poblado y en banda y con escalamiento&#8221;.<\/p>\n\n\n\n<p>La suerte para Wilson R., alias &#8220;Rubio&#8221;, el delincuente herido de un balazo, ven\u00eda acab\u00e1ndose desde hace una semana, ya que la brigada de investigaciones local encontr\u00f3 y recuper\u00f3 en su casa gran cantidad de elementos robados durante un raid delictivo de la banda que conformaba junto a otros. El juez Oscar Dur\u00e9s ya hab\u00eda solicitado su localizaci\u00f3n y aprehensi\u00f3n, lo que ahora se har\u00e1 efectiva.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El sargento volv\u00eda del trabajo a su casa cuando auxili\u00f3 a la v\u00edctima. Termin\u00f3 con<\/p>\n","protected":false},"author":1,"featured_media":486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/485"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=485"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/485\/revisions"}],"predecessor-version":[{"id":487,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/485\/revisions\/487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media\/486"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}