{"id":72,"date":"2022-07-26T14:11:35","date_gmt":"2022-07-26T14:11:35","guid":{"rendered":"https:\/\/elnordestediario.com\/?p=72"},"modified":"2022-08-10T00:03:38","modified_gmt":"2022-08-10T00:03:38","slug":"este-lunes-se-anunciara-el-nuevo-esquema-tarifario-por-regiones-para-agua-luz-y-gas","status":"publish","type":"post","link":"https:\/\/elnordestediario.com\/index.php\/2022\/07\/26\/este-lunes-se-anunciara-el-nuevo-esquema-tarifario-por-regiones-para-agua-luz-y-gas\/","title":{"rendered":"Este lunes se anunciar\u00e1 el nuevo esquema tarifario por regiones para agua, luz y gas"},"content":{"rendered":"\n<p>Las nuevas disposiciones que presentar\u00e1 el ministro Sergio Massa regir\u00e1n en las distintas zonas del pa\u00eds, &#8220;ya que se buscar\u00e1 respetar las particularidades de cada regi\u00f3n&#8221;.\u00a0<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"850\" height=\"565\" src=\"https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/image-10.png\" alt=\"\" class=\"wp-image-73\" srcset=\"https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/image-10.png 850w, https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/image-10-300x199.png 300w, https:\/\/elnordestediario.com\/wp-content\/uploads\/2022\/08\/image-10-768x510.png 768w\" sizes=\"(max-width: 850px) 100vw, 850px\" \/><figcaption>El ministro de Econom\u00eda, Sergio Massa, anunciar\u00e1 el pr\u00f3ximo martes los niveles de aumentos en las tarifas de gas, energ\u00eda el\u00e9ctrica, y agua que regir\u00e1n en las distintas regiones del pa\u00eds, &#8220;ya que se buscar\u00e1 respetar las particularidades de cada regi\u00f3n&#8221;, seg\u00fan indicaron fuentes del Palacio de Hacienda.<br>&#8220;No es lo mismo utilizar 400 kilowatts en Capital Federal y el Gran Buenos Aires, que en el noreste del pa\u00eds, donde se cocina con electricidad&#8221;, dijeron las fuentes.<br>El jefe del Palacio de Hacienda hab\u00eda manifestado durante su primera presentaci\u00f3n que &#8220;los casi 4 millones de hogares que no solicitaron subsidios en la segmentaci\u00f3n tarifaria &#8220;ser\u00e1n el primer corte&#8221; y dejar\u00e1n de percibir el beneficio, y adelant\u00f3 que se implementar\u00e1 un esquema para promover el ahorro en el consumo energ\u00e9tico.<br>Massa hab\u00eda indicado que &#8220;entre los m\u00e1s de 9 millones que s\u00ed pidieron mantener el subsidio se va a promover el ahorro por consumo&#8221;, y detall\u00f3 que &#8220;en luz se subsidiar\u00e1 hasta 400 kilowatts, en materia de gas la quita seguir\u00e1 la misma l\u00f3gica y en agua la aplicaci\u00f3n de la quita por segmentaci\u00f3n se iniciar\u00e1 en septiembre&#8221;.<br>En tanto, la portavoz de la Presidencia, Gabriela Cerruti, afirm\u00f3 este jueves que de los 9 millones de hogares que solicitaron mantener subsidios de luz y gas, &#8220;el 80% gasta menos de 400 kilowatts por mes, por lo que van a mantener el subsidio&#8221;, en relaci\u00f3n con la segmentaci\u00f3n de tarifas encarada por el Gobierno nacional.<br>&#8220;Del 20% restante no esperamos que paguen m\u00e1s tarifas sino que reduzcan un poco sus gastos&#8221; energ\u00e9ticos, agreg\u00f3 Cerruti durante su habitual conferencia de prensa semanal en la que brind\u00f3 pormenores de la reuni\u00f3n mantenida este jueves entre el presidente, Alberto Fern\u00e1ndez, y su ministro de Econom\u00eda, Sergio Massa.<br>La funcionaria tambi\u00e9n indic\u00f3 que la nueva pol\u00edtica en relaci\u00f3n con las tarifas no tiene solamente un objetivo fiscal, sino que tambi\u00e9n persigue &#8220;una idea de empezar a considerar que tanto el gas como la luz son bienes de dif\u00edcil acceso en el mundo, que son bienes que tenemos que cuidar porque tienen que ver con la crisis clim\u00e1tica, y que por lo tanto el ahorro tiene que pasar a ser una acci\u00f3n voluntaria pero persistente de los argentinos y las argentinas&#8221;.<br>El ministro dar\u00e1 a conocer este viernes qui\u00e9n lo acompa\u00f1ara en la estrat\u00e9gica secretar\u00eda de Pol\u00edtica Econ\u00f3mica, que se considera como un viceministro, a\u00f1adieron esas mismas fuentes oficiales.<br>Al mismo tiempo, un portavoz del Palacio de Hacienda confirm\u00f3 que Massa realizar\u00e1, entre la \u00faltima semana de agosto y la primera semana de septiembre, un gira por los Estados Unidos, Francia y Qatar, donde dialogar\u00e1 con los organismos internacionales de cr\u00e9dito y bancos de inversi\u00f3n.<br>El ministro dijo el mi\u00e9rcoles que tres instituciones financieras internacionales y un fondo soberano ofrecieron &#8220;cuatro ofertas de Repo: para fortalecimiento de reservas y recompra de deuda soberana&#8221;.<br>Massa, evalu\u00f3 este jueves con el presidente del Banco Interamericano de Desarrollo (BID), Mauricio Claver-Carone, el &#8220;estado de situaci\u00f3n de los prestamos existentes y las nuevas oportunidades de financiaci\u00f3n&#8221;.<br>&#8220;Agradezco a Mauricio Claver-Carone del BID la reuni\u00f3n mantenida en la que evaluamos el estado de situaci\u00f3n de los pr\u00e9stamos existentes y las nuevas oportunidades de financiaci\u00f3n para promover el desarrollo inclusivo y desarrollar obras de infraestructura en nuestro pa\u00eds&#8221;, afirm\u00f3 Massa en su cuenta en Twitter.<br>El mi\u00e9rcoles, Massa se comprometi\u00f3 a gestionar la aceleraci\u00f3n de desembolsos de organismos internacionales, cuyos cr\u00e9ditos est\u00e1n en carpeta pero a\u00fan faltan aprobar y, otros ya hab\u00edan sido aprobados pero se encontraban demorados, por US$ 1.200 millones; as\u00ed como tambi\u00e9n un nuevo programa con CAF por US$ 750 millones adicionales.<br>Desde la cartera econ\u00f3mica se confirm\u00f3 que el secretario de Agricultura Ganader\u00eda y Pesca, Juan Jos\u00e9 Bahillo, se reuni\u00f3 con su antecesor, Juli\u00e1n Dom\u00ednguez, para trazar una hoja de ruta de temas a impulsar, y ya tomaron contacto con el presidente de la Sociedad Rural Argentina, Nicol\u00e1s Pino, para mantener una reuni\u00f3n, la semana pr\u00f3xima, con los integrantes de la Mesa de Enlace.<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las nuevas disposiciones que presentar\u00e1 el ministro Sergio Massa regir\u00e1n en las distintas zonas del<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"_links":{"self":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/72"}],"collection":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/comments?post=72"}],"version-history":[{"count":1,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/72\/revisions"}],"predecessor-version":[{"id":74,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/posts\/72\/revisions\/74"}],"wp:attachment":[{"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/media?parent=72"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/categories?post=72"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elnordestediario.com\/index.php\/wp-json\/wp\/v2\/tags?post=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}